{"id":72,"count":1,"description":"","link":"https:\/\/techortrade.co.uk\/sell\/product-category\/ipad\/","name":"iPad","slug":"ipad","taxonomy":"product_cat","parent":0,"meta":{"order":["0"],"product_count_product_cat":["1"],"display_type":[""],"thumbnail_id":["3845"],"_wc_facebook_google_product_category":[""],"_wc_facebook_enhanced_catalog_attributes___optional_selector":[null],"rank_math_title":["%term% %sep% %sitename%"],"rank_math_description":["%term_description%"],"rank_math_robots":["a:1:{i:0;s:5:\"index\";}"],"rank_math_focus_keyword":[""],"rank_math_canonical_url":[""]},"menu_order":0,"_links":{"self":[{"href":"https:\/\/techortrade.co.uk\/sell\/wp-json\/wp\/v2\/product_cat\/72","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/techortrade.co.uk\/sell\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/techortrade.co.uk\/sell\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/techortrade.co.uk\/sell\/wp-json\/wp\/v2\/product?product_cat=72"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}